{"id":78149,"date":"2025-12-09T14:41:15","date_gmt":"2025-12-09T14:41:15","guid":{"rendered":"https:\/\/dev.tradesilvania.com\/wallet\/solana\/"},"modified":"2025-12-09T14:41:15","modified_gmt":"2025-12-09T14:41:15","slug":"solana","status":"publish","type":"wallet","link":"https:\/\/www.tradesilvania.com\/en\/wallet\/solana\/","title":{"rendered":"Solana"},"content":{"rendered":"<p>Wallet page for <\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-78149","wallet","type-wallet","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Solana - Tradesilvania<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tradesilvania.com\/en\/wallet\/solana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solana - Tradesilvania\" \/>\n<meta property=\"og:description\" content=\"Wallet page for\" \/>\n<meta property=\"og:site_name\" content=\"Tradesilvania\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/wallet\\\/solana\\\/\",\"url\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/wallet\\\/solana\\\/\",\"name\":\"Solana - Tradesilvania\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/#website\"},\"datePublished\":\"2025-12-09T14:41:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/wallet\\\/solana\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/wallet\\\/solana\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/wallet\\\/solana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/\",\"name\":\"Tradesilvania\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/#organization\",\"name\":\"Tradesilvania\",\"url\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tradesilvania.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo.svg.png\",\"contentUrl\":\"https:\\\/\\\/www.tradesilvania.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo.svg.png\",\"width\":1023,\"height\":138,\"caption\":\"Tradesilvania\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tradesilvania.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solana - Tradesilvania","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tradesilvania.com\/en\/wallet\/solana\/","og_locale":"en_US","og_type":"article","og_title":"Solana - Tradesilvania","og_description":"Wallet page for","og_site_name":"Tradesilvania","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tradesilvania.com\/en\/wallet\/solana\/","url":"https:\/\/www.tradesilvania.com\/en\/wallet\/solana\/","name":"Solana - Tradesilvania","isPartOf":{"@id":"https:\/\/www.tradesilvania.com\/en\/#website"},"datePublished":"2025-12-09T14:41:15+00:00","breadcrumb":{"@id":"https:\/\/www.tradesilvania.com\/en\/wallet\/solana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tradesilvania.com\/en\/wallet\/solana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tradesilvania.com\/en\/wallet\/solana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tradesilvania.com\/en\/"},{"@type":"ListItem","position":2,"name":"Solana"}]},{"@type":"WebSite","@id":"https:\/\/www.tradesilvania.com\/en\/#website","url":"https:\/\/www.tradesilvania.com\/en\/","name":"Tradesilvania","description":"","publisher":{"@id":"https:\/\/www.tradesilvania.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tradesilvania.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.tradesilvania.com\/en\/#organization","name":"Tradesilvania","url":"https:\/\/www.tradesilvania.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tradesilvania.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.tradesilvania.com\/wp-content\/uploads\/2025\/09\/logo.svg.png","contentUrl":"https:\/\/www.tradesilvania.com\/wp-content\/uploads\/2025\/09\/logo.svg.png","width":1023,"height":138,"caption":"Tradesilvania"},"image":{"@id":"https:\/\/www.tradesilvania.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/wallet\/78149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/wallet"}],"about":[{"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/types\/wallet"}],"version-history":[{"count":1,"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/wallet\/78149\/revisions"}],"predecessor-version":[{"id":78157,"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/wallet\/78149\/revisions\/78157"}],"wp:attachment":[{"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/media?parent=78149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}