{"id":79067,"date":"2025-12-09T14:41:38","date_gmt":"2025-12-09T14:41:38","guid":{"rendered":"https:\/\/dev.tradesilvania.com\/wallet\/aave\/"},"modified":"2025-12-09T14:41:38","modified_gmt":"2025-12-09T14:41:38","slug":"aave","status":"publish","type":"wallet","link":"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/","title":{"rendered":"Aave"},"content":{"rendered":"<p>Wallet page for <\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-79067","wallet","type-wallet","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aave - Tradesilvania<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aave - Tradesilvania\" \/>\n<meta property=\"og:description\" content=\"Wallet page for\" \/>\n<meta property=\"og:site_name\" content=\"Tradesilvania\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/\",\"url\":\"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/\",\"name\":\"Aave - Tradesilvania\",\"isPartOf\":{\"@id\":\"https:\/\/www.tradesilvania.com\/en\/#website\"},\"datePublished\":\"2025-12-09T14:41:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tradesilvania.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aave\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tradesilvania.com\/en\/#website\",\"url\":\"https:\/\/www.tradesilvania.com\/en\/\",\"name\":\"Tradesilvania\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.tradesilvania.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tradesilvania.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tradesilvania.com\/en\/#organization\",\"name\":\"Tradesilvania\",\"url\":\"https:\/\/www.tradesilvania.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.tradesilvania.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tradesilvania.com\/wp-content\/uploads\/2025\/09\/logo.svg.png\",\"contentUrl\":\"https:\/\/www.tradesilvania.com\/wp-content\/uploads\/2025\/09\/logo.svg.png\",\"width\":1023,\"height\":138,\"caption\":\"Tradesilvania\"},\"image\":{\"@id\":\"https:\/\/www.tradesilvania.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aave - Tradesilvania","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/","og_locale":"en_US","og_type":"article","og_title":"Aave - Tradesilvania","og_description":"Wallet page for","og_site_name":"Tradesilvania","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/","url":"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/","name":"Aave - Tradesilvania","isPartOf":{"@id":"https:\/\/www.tradesilvania.com\/en\/#website"},"datePublished":"2025-12-09T14:41:38+00:00","breadcrumb":{"@id":"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tradesilvania.com\/en\/wallet\/aave\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tradesilvania.com\/en\/"},{"@type":"ListItem","position":2,"name":"Aave"}]},{"@type":"WebSite","@id":"https:\/\/www.tradesilvania.com\/en\/#website","url":"https:\/\/www.tradesilvania.com\/en\/","name":"Tradesilvania","description":"","publisher":{"@id":"https:\/\/www.tradesilvania.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tradesilvania.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.tradesilvania.com\/en\/#organization","name":"Tradesilvania","url":"https:\/\/www.tradesilvania.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tradesilvania.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.tradesilvania.com\/wp-content\/uploads\/2025\/09\/logo.svg.png","contentUrl":"https:\/\/www.tradesilvania.com\/wp-content\/uploads\/2025\/09\/logo.svg.png","width":1023,"height":138,"caption":"Tradesilvania"},"image":{"@id":"https:\/\/www.tradesilvania.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/wallet\/79067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/wallet"}],"about":[{"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/types\/wallet"}],"version-history":[{"count":1,"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/wallet\/79067\/revisions"}],"predecessor-version":[{"id":79075,"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/wallet\/79067\/revisions\/79075"}],"wp:attachment":[{"href":"https:\/\/www.tradesilvania.com\/en\/wp-json\/wp\/v2\/media?parent=79067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}